{"id":5718,"date":"2024-04-26T11:00:27","date_gmt":"2024-04-26T02:00:27","guid":{"rendered":"https:\/\/open-insight.net\/glossary\/?post_type=contents&#038;p=5718"},"modified":"2024-04-26T11:00:27","modified_gmt":"2024-04-26T02:00:27","slug":"1622","status":"publish","type":"contents","link":"https:\/\/open-insight.net\/glossary\/contents\/1622\/","title":{"rendered":"\u8003\u8ab2\u8005\u7814\u4fee\u3068\u306f"},"content":{"rendered":"<p>\u4eba\u4e8b\u8a55\u4fa1\u7814\u4fee\u3068\u306f\u3001\u4eba\u4e8b\u8a55\u4fa1\u3092\u884c\u3046\u30b9\u30bf\u30c3\u30d5\u304c\u305d\u306e\u5236\u5ea6\u3078\u306e\u7406\u89e3\u3092\u6df1\u5316\u3055\u305b\u3001\u516c\u6b63\u306a\u8a55\u4fa1\u6280\u8853\u3092\u5b66\u3076\u305f\u3081\u306e\u30c8\u30ec\u30fc\u30cb\u30f3\u30b0\u3067\u3059\u3002\u4e3b\u8981\u306a\u30d7\u30ed\u30b0\u30e9\u30e0\u3068\u3057\u3066\u30011.\u76ee\u6a19\u8a2d\u5b9a\u306b\u5bfe\u3059\u308b\u6b63\u78ba\u306a\u7406\u89e3\u3068\u305d\u306e\u5b9f\u884c\u306e\u65b9\u6cd5 2.\u88ab\u8a55\u4fa1\u8005\u306e\u5177\u4f53\u7684\u306a\u7d50\u679c\u3084\u884c\u52d5\u306b\u57fa\u3065\u3044\u305f\u4eba\u4e8b\u8a55\u4fa1\u306e\u65b9\u6cd5 3.\u88ab\u8a55\u4fa1\u8005\u306e\u80b2\u6210\u30fb\u6559\u80b2\u306b\u3064\u306a\u304c\u308b\u6709\u52b9\u306a\u30d5\u30a3\u30fc\u30c9\u30d0\u30c3\u30af\u306e\u65b9\u6cd5\u3001\u3068\u3044\u3046\u4e09\u3064\u306e\u8981\u7d20\u3092\u5b66\u3076\u3053\u3068\u304c\u4e00\u822c\u7684\u3067\u3059\u3002\u4eba\u4e8b\u8a55\u4fa1\u306f\u3001\u7d66\u4e0e\u3084\u30dc\u30fc\u30ca\u30b9\u3001\u5f79\u8077\u306a\u3069\u306e\u5f85\u9047\u3092\u6c7a\u5b9a\u3059\u308b\u305f\u3081\u306e\u67fb\u5b9a\u304c\u4e3b\u76ee\u7684\u3068\u307f\u306a\u3055\u308c\u308b\u3053\u3068\u304c\u591a\u3044\u3067\u3059\u3002&#8217;<\/p>\n","protected":false},"excerpt":{"rendered":"\u4eba\u4e8b\u8a55\u4fa1\u7814\u4fee\u3068\u306f\u3001\u4eba\u4e8b\u8a55\u4fa1\u3092\u884c\u3046\u30b9\u30bf\u30c3\u30d5\u304c\u305d\u306e\u5236\u5ea6\u3078\u306e\u7406\u89e3\u3092\u6df1\u5316\u3055\u305b\u3001\u516c\u6b63\u306a\u8a55\u4fa1\u6280\u8853\u3092\u5b66\u3076\u305f\u3081\u306e\u30c8\u30ec\u30fc\u30cb\u30f3\u30b0\u3067\u3059\u3002\u4e3b\u8981\u306a\u30d7\u30ed\u30b0\u30e9\u30e0\u3068\u3057\u3066\u30011.\u76ee\u6a19\u8a2d\u5b9a\u306b\u5bfe\u3059\u308b\u6b63\u78ba\u306a\u7406\u89e3\u3068\u305d\u306e\u5b9f\u884c\u306e\u65b9\u6cd5 2.\u88ab\u8a55\u4fa1\u8005\u306e\u5177\u4f53\u7684\u306a\u7d50\u679c\u3084\u884c\u52d5\u306b [&hellip;]","protected":false},"featured_media":5719,"template":"","term_category":[123,126],"alphabetical-order":[16,5],"contents_tag":[5825,5826,967,2928,5824],"class_list":["post-5718","contents","type-contents","status-publish","has-post-thumbnail","hentry","term_category-business_theme","term_category-human_resources","alphabetical-order-ko","alphabetical-order-japanese","contents_tag-5825","contents_tag-5826","contents_tag-967","contents_tag-2928","contents_tag-5824"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u8003\u8ab2\u8005\u7814\u4fee\u3068\u306f - Open Insight \u7528\u8a9e\u96c6\uff1a\u30d3\u30b8\u30cd\u30b9\u306b\u5fc5\u8981\u306a\u7528\u8a9e\u3092\u30ef\u30f3\u30b9\u30c8\u30c3\u30d7\u3067\u7d39\u4ecb<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/open-insight.net\/glossary\/contents\/1622\/\" \/>\n<meta property=\"og:locale\" content=\"ja_JP\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u8003\u8ab2\u8005\u7814\u4fee\u3068\u306f - Open Insight \u7528\u8a9e\u96c6\uff1a\u30d3\u30b8\u30cd\u30b9\u306b\u5fc5\u8981\u306a\u7528\u8a9e\u3092\u30ef\u30f3\u30b9\u30c8\u30c3\u30d7\u3067\u7d39\u4ecb\" \/>\n<meta property=\"og:description\" content=\"\u4eba\u4e8b\u8a55\u4fa1\u7814\u4fee\u3068\u306f\u3001\u4eba\u4e8b\u8a55\u4fa1\u3092\u884c\u3046\u30b9\u30bf\u30c3\u30d5\u304c\u305d\u306e\u5236\u5ea6\u3078\u306e\u7406\u89e3\u3092\u6df1\u5316\u3055\u305b\u3001\u516c\u6b63\u306a\u8a55\u4fa1\u6280\u8853\u3092\u5b66\u3076\u305f\u3081\u306e\u30c8\u30ec\u30fc\u30cb\u30f3\u30b0\u3067\u3059\u3002\u4e3b\u8981\u306a\u30d7\u30ed\u30b0\u30e9\u30e0\u3068\u3057\u3066\u30011.\u76ee\u6a19\u8a2d\u5b9a\u306b\u5bfe\u3059\u308b\u6b63\u78ba\u306a\u7406\u89e3\u3068\u305d\u306e\u5b9f\u884c\u306e\u65b9\u6cd5 2.\u88ab\u8a55\u4fa1\u8005\u306e\u5177\u4f53\u7684\u306a\u7d50\u679c\u3084\u884c\u52d5\u306b [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/open-insight.net\/glossary\/contents\/1622\/\" \/>\n<meta property=\"og:site_name\" content=\"Open Insight \u7528\u8a9e\u96c6\uff1a\u30d3\u30b8\u30cd\u30b9\u306b\u5fc5\u8981\u306a\u7528\u8a9e\u3092\u30ef\u30f3\u30b9\u30c8\u30c3\u30d7\u3067\u7d39\u4ecb\" \/>\n<meta property=\"og:image\" content=\"https:\/\/open-insight.net\/glossary\/wp-content\/uploads\/sites\/2\/2024\/04\/9-6-16-127-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/open-insight.net\/glossary\/contents\/1622\/\",\"url\":\"https:\/\/open-insight.net\/glossary\/contents\/1622\/\",\"name\":\"\u8003\u8ab2\u8005\u7814\u4fee\u3068\u306f - Open Insight \u7528\u8a9e\u96c6\uff1a\u30d3\u30b8\u30cd\u30b9\u306b\u5fc5\u8981\u306a\u7528\u8a9e\u3092\u30ef\u30f3\u30b9\u30c8\u30c3\u30d7\u3067\u7d39\u4ecb\",\"isPartOf\":{\"@id\":\"https:\/\/open-insight.net\/glossary\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/open-insight.net\/glossary\/contents\/1622\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/open-insight.net\/glossary\/contents\/1622\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/open-insight.net\/glossary\/wp-content\/uploads\/sites\/2\/2024\/04\/9-6-16-127-1.png\",\"datePublished\":\"2024-04-26T02:00:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/open-insight.net\/glossary\/contents\/1622\/#breadcrumb\"},\"inLanguage\":\"ja\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/open-insight.net\/glossary\/contents\/1622\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ja\",\"@id\":\"https:\/\/open-insight.net\/glossary\/contents\/1622\/#primaryimage\",\"url\":\"https:\/\/open-insight.net\/glossary\/wp-content\/uploads\/sites\/2\/2024\/04\/9-6-16-127-1.png\",\"contentUrl\":\"https:\/\/open-insight.net\/glossary\/wp-content\/uploads\/sites\/2\/2024\/04\/9-6-16-127-1.png\",\"width\":1200,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/open-insight.net\/glossary\/contents\/1622\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u30db\u30fc\u30e0\",\"item\":\"https:\/\/open-insight.net\/glossary\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u7528\u8a9e\",\"item\":\"https:\/\/open-insight.net\/glossary\/contents\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u8003\u8ab2\u8005\u7814\u4fee\u3068\u306f\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/open-insight.net\/glossary\/#website\",\"url\":\"https:\/\/open-insight.net\/glossary\/\",\"name\":\"Open Insight \u7528\u8a9e\u96c6\u30b5\u30a4\u30c8\uff1a\u4f01\u696d\u6210\u9577\u306e\u77e5\u898b\u3068\u6226\u7565\u3092\u63d0\u4f9b\",\"description\":\"Open Insight \u7528\u8a9e\u96c6\u30b5\u30a4\u30c8\u306f\u3001\u4f01\u696d\u306e\u6210\u9577\u3068\u767a\u5c55\u306b\u5fc5\u8981\u306a\u60c5\u5831\u3092\u4e00\u7b87\u6240\u3067\u63d0\u4f9b\u3057\u307e\u3059\u3002\",\"publisher\":{\"@id\":\"https:\/\/open-insight.net\/glossary\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/open-insight.net\/glossary\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ja\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/open-insight.net\/glossary\/#organization\",\"name\":\"Open Insight \u7528\u8a9e\u96c6\u30b5\u30a4\u30c8\uff1a\u4f01\u696d\u6210\u9577\u306e\u77e5\u898b\u3068\u6226\u7565\u3092\u63d0\u4f9b\",\"url\":\"https:\/\/open-insight.net\/glossary\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ja\",\"@id\":\"https:\/\/open-insight.net\/glossary\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/open-insight.net\/glossary\/wp-content\/uploads\/sites\/2\/2024\/02\/og-image.png\",\"contentUrl\":\"https:\/\/open-insight.net\/glossary\/wp-content\/uploads\/sites\/2\/2024\/02\/og-image.png\",\"width\":1200,\"height\":675,\"caption\":\"Open Insight \u7528\u8a9e\u96c6\u30b5\u30a4\u30c8\uff1a\u4f01\u696d\u6210\u9577\u306e\u77e5\u898b\u3068\u6226\u7565\u3092\u63d0\u4f9b\"},\"image\":{\"@id\":\"https:\/\/open-insight.net\/glossary\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u8003\u8ab2\u8005\u7814\u4fee\u3068\u306f - Open Insight \u7528\u8a9e\u96c6\uff1a\u30d3\u30b8\u30cd\u30b9\u306b\u5fc5\u8981\u306a\u7528\u8a9e\u3092\u30ef\u30f3\u30b9\u30c8\u30c3\u30d7\u3067\u7d39\u4ecb","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/open-insight.net\/glossary\/contents\/1622\/","og_locale":"ja_JP","og_type":"article","og_title":"\u8003\u8ab2\u8005\u7814\u4fee\u3068\u306f - Open Insight \u7528\u8a9e\u96c6\uff1a\u30d3\u30b8\u30cd\u30b9\u306b\u5fc5\u8981\u306a\u7528\u8a9e\u3092\u30ef\u30f3\u30b9\u30c8\u30c3\u30d7\u3067\u7d39\u4ecb","og_description":"\u4eba\u4e8b\u8a55\u4fa1\u7814\u4fee\u3068\u306f\u3001\u4eba\u4e8b\u8a55\u4fa1\u3092\u884c\u3046\u30b9\u30bf\u30c3\u30d5\u304c\u305d\u306e\u5236\u5ea6\u3078\u306e\u7406\u89e3\u3092\u6df1\u5316\u3055\u305b\u3001\u516c\u6b63\u306a\u8a55\u4fa1\u6280\u8853\u3092\u5b66\u3076\u305f\u3081\u306e\u30c8\u30ec\u30fc\u30cb\u30f3\u30b0\u3067\u3059\u3002\u4e3b\u8981\u306a\u30d7\u30ed\u30b0\u30e9\u30e0\u3068\u3057\u3066\u30011.\u76ee\u6a19\u8a2d\u5b9a\u306b\u5bfe\u3059\u308b\u6b63\u78ba\u306a\u7406\u89e3\u3068\u305d\u306e\u5b9f\u884c\u306e\u65b9\u6cd5 2.\u88ab\u8a55\u4fa1\u8005\u306e\u5177\u4f53\u7684\u306a\u7d50\u679c\u3084\u884c\u52d5\u306b [&hellip;]","og_url":"https:\/\/open-insight.net\/glossary\/contents\/1622\/","og_site_name":"Open Insight \u7528\u8a9e\u96c6\uff1a\u30d3\u30b8\u30cd\u30b9\u306b\u5fc5\u8981\u306a\u7528\u8a9e\u3092\u30ef\u30f3\u30b9\u30c8\u30c3\u30d7\u3067\u7d39\u4ecb","og_image":[{"width":1200,"height":600,"url":"https:\/\/open-insight.net\/glossary\/wp-content\/uploads\/sites\/2\/2024\/04\/9-6-16-127-1.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/open-insight.net\/glossary\/contents\/1622\/","url":"https:\/\/open-insight.net\/glossary\/contents\/1622\/","name":"\u8003\u8ab2\u8005\u7814\u4fee\u3068\u306f - Open Insight \u7528\u8a9e\u96c6\uff1a\u30d3\u30b8\u30cd\u30b9\u306b\u5fc5\u8981\u306a\u7528\u8a9e\u3092\u30ef\u30f3\u30b9\u30c8\u30c3\u30d7\u3067\u7d39\u4ecb","isPartOf":{"@id":"https:\/\/open-insight.net\/glossary\/#website"},"primaryImageOfPage":{"@id":"https:\/\/open-insight.net\/glossary\/contents\/1622\/#primaryimage"},"image":{"@id":"https:\/\/open-insight.net\/glossary\/contents\/1622\/#primaryimage"},"thumbnailUrl":"https:\/\/open-insight.net\/glossary\/wp-content\/uploads\/sites\/2\/2024\/04\/9-6-16-127-1.png","datePublished":"2024-04-26T02:00:27+00:00","breadcrumb":{"@id":"https:\/\/open-insight.net\/glossary\/contents\/1622\/#breadcrumb"},"inLanguage":"ja","potentialAction":[{"@type":"ReadAction","target":["https:\/\/open-insight.net\/glossary\/contents\/1622\/"]}]},{"@type":"ImageObject","inLanguage":"ja","@id":"https:\/\/open-insight.net\/glossary\/contents\/1622\/#primaryimage","url":"https:\/\/open-insight.net\/glossary\/wp-content\/uploads\/sites\/2\/2024\/04\/9-6-16-127-1.png","contentUrl":"https:\/\/open-insight.net\/glossary\/wp-content\/uploads\/sites\/2\/2024\/04\/9-6-16-127-1.png","width":1200,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/open-insight.net\/glossary\/contents\/1622\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u30db\u30fc\u30e0","item":"https:\/\/open-insight.net\/glossary\/"},{"@type":"ListItem","position":2,"name":"\u7528\u8a9e","item":"https:\/\/open-insight.net\/glossary\/contents\/"},{"@type":"ListItem","position":3,"name":"\u8003\u8ab2\u8005\u7814\u4fee\u3068\u306f"}]},{"@type":"WebSite","@id":"https:\/\/open-insight.net\/glossary\/#website","url":"https:\/\/open-insight.net\/glossary\/","name":"Open Insight \u7528\u8a9e\u96c6\u30b5\u30a4\u30c8\uff1a\u4f01\u696d\u6210\u9577\u306e\u77e5\u898b\u3068\u6226\u7565\u3092\u63d0\u4f9b","description":"Open Insight \u7528\u8a9e\u96c6\u30b5\u30a4\u30c8\u306f\u3001\u4f01\u696d\u306e\u6210\u9577\u3068\u767a\u5c55\u306b\u5fc5\u8981\u306a\u60c5\u5831\u3092\u4e00\u7b87\u6240\u3067\u63d0\u4f9b\u3057\u307e\u3059\u3002","publisher":{"@id":"https:\/\/open-insight.net\/glossary\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/open-insight.net\/glossary\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ja"},{"@type":"Organization","@id":"https:\/\/open-insight.net\/glossary\/#organization","name":"Open Insight \u7528\u8a9e\u96c6\u30b5\u30a4\u30c8\uff1a\u4f01\u696d\u6210\u9577\u306e\u77e5\u898b\u3068\u6226\u7565\u3092\u63d0\u4f9b","url":"https:\/\/open-insight.net\/glossary\/","logo":{"@type":"ImageObject","inLanguage":"ja","@id":"https:\/\/open-insight.net\/glossary\/#\/schema\/logo\/image\/","url":"https:\/\/open-insight.net\/glossary\/wp-content\/uploads\/sites\/2\/2024\/02\/og-image.png","contentUrl":"https:\/\/open-insight.net\/glossary\/wp-content\/uploads\/sites\/2\/2024\/02\/og-image.png","width":1200,"height":675,"caption":"Open Insight \u7528\u8a9e\u96c6\u30b5\u30a4\u30c8\uff1a\u4f01\u696d\u6210\u9577\u306e\u77e5\u898b\u3068\u6226\u7565\u3092\u63d0\u4f9b"},"image":{"@id":"https:\/\/open-insight.net\/glossary\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/open-insight.net\/glossary\/wp-json\/wp\/v2\/contents\/5718","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/open-insight.net\/glossary\/wp-json\/wp\/v2\/contents"}],"about":[{"href":"https:\/\/open-insight.net\/glossary\/wp-json\/wp\/v2\/types\/contents"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/open-insight.net\/glossary\/wp-json\/wp\/v2\/media\/5719"}],"wp:attachment":[{"href":"https:\/\/open-insight.net\/glossary\/wp-json\/wp\/v2\/media?parent=5718"}],"wp:term":[{"taxonomy":"term_category","embeddable":true,"href":"https:\/\/open-insight.net\/glossary\/wp-json\/wp\/v2\/term_category?post=5718"},{"taxonomy":"alphabetical-order","embeddable":true,"href":"https:\/\/open-insight.net\/glossary\/wp-json\/wp\/v2\/alphabetical-order?post=5718"},{"taxonomy":"contents_tag","embeddable":true,"href":"https:\/\/open-insight.net\/glossary\/wp-json\/wp\/v2\/contents_tag?post=5718"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}