{"id":5854,"date":"2024-04-26T11:00:59","date_gmt":"2024-04-26T02:00:59","guid":{"rendered":"https:\/\/open-insight.net\/glossary\/?post_type=contents&#038;p=5854"},"modified":"2024-04-26T11:00:59","modified_gmt":"2024-04-26T02:00:59","slug":"1690","status":"publish","type":"contents","link":"https:\/\/open-insight.net\/glossary\/contents\/1690\/","title":{"rendered":"\u56fa\u5b9a\u91d1\u5229\u3068\u306f"},"content":{"rendered":"<p>\u91d1\u878d\u6a5f\u95a2\u306b\u9810\u3051\u5165\u308c\u305f\u969b\u306e\u5e74\u9593\u5229\u606f\u304c\u3001\u671f\u9593\u6e80\u4e86\u307e\u3067\u5909\u52d5\u3057\u306a\u3044\u3001\u4e00\u5b9a\u306e\u91d1\u5229\u3092\u6307\u3057\u307e\u3059\u3002&#8217;<\/p>\n","protected":false},"excerpt":{"rendered":"\u91d1\u878d\u6a5f\u95a2\u306b\u9810\u3051\u5165\u308c\u305f\u969b\u306e\u5e74\u9593\u5229\u606f\u304c\u3001\u671f\u9593\u6e80\u4e86\u307e\u3067\u5909\u52d5\u3057\u306a\u3044\u3001\u4e00\u5b9a\u306e\u91d1\u5229\u3092\u6307\u3057\u307e\u3059\u3002&#8217;","protected":false},"featured_media":5855,"template":"","term_category":[123,128],"alphabetical-order":[16,5],"contents_tag":[6026,6025,4546,1999,2284],"class_list":["post-5854","contents","type-contents","status-publish","has-post-thumbnail","hentry","term_category-business_theme","term_category-finance","alphabetical-order-ko","alphabetical-order-japanese","contents_tag-6026","contents_tag-6025","contents_tag-4546","contents_tag-1999","contents_tag-2284"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u56fa\u5b9a\u91d1\u5229\u3068\u306f - Open Insight \u7528\u8a9e\u96c6\uff1a\u30d3\u30b8\u30cd\u30b9\u306b\u5fc5\u8981\u306a\u7528\u8a9e\u3092\u30ef\u30f3\u30b9\u30c8\u30c3\u30d7\u3067\u7d39\u4ecb<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/open-insight.net\/glossary\/contents\/1690\/\" \/>\n<meta property=\"og:locale\" content=\"ja_JP\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u56fa\u5b9a\u91d1\u5229\u3068\u306f - Open Insight \u7528\u8a9e\u96c6\uff1a\u30d3\u30b8\u30cd\u30b9\u306b\u5fc5\u8981\u306a\u7528\u8a9e\u3092\u30ef\u30f3\u30b9\u30c8\u30c3\u30d7\u3067\u7d39\u4ecb\" \/>\n<meta property=\"og:description\" content=\"\u91d1\u878d\u6a5f\u95a2\u306b\u9810\u3051\u5165\u308c\u305f\u969b\u306e\u5e74\u9593\u5229\u606f\u304c\u3001\u671f\u9593\u6e80\u4e86\u307e\u3067\u5909\u52d5\u3057\u306a\u3044\u3001\u4e00\u5b9a\u306e\u91d1\u5229\u3092\u6307\u3057\u307e\u3059\u3002&#8217;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/open-insight.net\/glossary\/contents\/1690\/\" \/>\n<meta property=\"og:site_name\" content=\"Open Insight \u7528\u8a9e\u96c6\uff1a\u30d3\u30b8\u30cd\u30b9\u306b\u5fc5\u8981\u306a\u7528\u8a9e\u3092\u30ef\u30f3\u30b9\u30c8\u30c3\u30d7\u3067\u7d39\u4ecb\" \/>\n<meta property=\"og:image\" content=\"https:\/\/open-insight.net\/glossary\/wp-content\/uploads\/sites\/2\/2024\/04\/9-6-16-195-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/open-insight.net\/glossary\/contents\/1690\/\",\"url\":\"https:\/\/open-insight.net\/glossary\/contents\/1690\/\",\"name\":\"\u56fa\u5b9a\u91d1\u5229\u3068\u306f - Open Insight \u7528\u8a9e\u96c6\uff1a\u30d3\u30b8\u30cd\u30b9\u306b\u5fc5\u8981\u306a\u7528\u8a9e\u3092\u30ef\u30f3\u30b9\u30c8\u30c3\u30d7\u3067\u7d39\u4ecb\",\"isPartOf\":{\"@id\":\"https:\/\/open-insight.net\/glossary\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/open-insight.net\/glossary\/contents\/1690\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/open-insight.net\/glossary\/contents\/1690\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/open-insight.net\/glossary\/wp-content\/uploads\/sites\/2\/2024\/04\/9-6-16-195-1.png\",\"datePublished\":\"2024-04-26T02:00:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/open-insight.net\/glossary\/contents\/1690\/#breadcrumb\"},\"inLanguage\":\"ja\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/open-insight.net\/glossary\/contents\/1690\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ja\",\"@id\":\"https:\/\/open-insight.net\/glossary\/contents\/1690\/#primaryimage\",\"url\":\"https:\/\/open-insight.net\/glossary\/wp-content\/uploads\/sites\/2\/2024\/04\/9-6-16-195-1.png\",\"contentUrl\":\"https:\/\/open-insight.net\/glossary\/wp-content\/uploads\/sites\/2\/2024\/04\/9-6-16-195-1.png\",\"width\":1200,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/open-insight.net\/glossary\/contents\/1690\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u30db\u30fc\u30e0\",\"item\":\"https:\/\/open-insight.net\/glossary\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u7528\u8a9e\",\"item\":\"https:\/\/open-insight.net\/glossary\/contents\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u56fa\u5b9a\u91d1\u5229\u3068\u306f\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/open-insight.net\/glossary\/#website\",\"url\":\"https:\/\/open-insight.net\/glossary\/\",\"name\":\"Open Insight \u7528\u8a9e\u96c6\u30b5\u30a4\u30c8\uff1a\u4f01\u696d\u6210\u9577\u306e\u77e5\u898b\u3068\u6226\u7565\u3092\u63d0\u4f9b\",\"description\":\"Open Insight \u7528\u8a9e\u96c6\u30b5\u30a4\u30c8\u306f\u3001\u4f01\u696d\u306e\u6210\u9577\u3068\u767a\u5c55\u306b\u5fc5\u8981\u306a\u60c5\u5831\u3092\u4e00\u7b87\u6240\u3067\u63d0\u4f9b\u3057\u307e\u3059\u3002\",\"publisher\":{\"@id\":\"https:\/\/open-insight.net\/glossary\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/open-insight.net\/glossary\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ja\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/open-insight.net\/glossary\/#organization\",\"name\":\"Open Insight \u7528\u8a9e\u96c6\u30b5\u30a4\u30c8\uff1a\u4f01\u696d\u6210\u9577\u306e\u77e5\u898b\u3068\u6226\u7565\u3092\u63d0\u4f9b\",\"url\":\"https:\/\/open-insight.net\/glossary\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ja\",\"@id\":\"https:\/\/open-insight.net\/glossary\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/open-insight.net\/glossary\/wp-content\/uploads\/sites\/2\/2024\/02\/og-image.png\",\"contentUrl\":\"https:\/\/open-insight.net\/glossary\/wp-content\/uploads\/sites\/2\/2024\/02\/og-image.png\",\"width\":1200,\"height\":675,\"caption\":\"Open Insight \u7528\u8a9e\u96c6\u30b5\u30a4\u30c8\uff1a\u4f01\u696d\u6210\u9577\u306e\u77e5\u898b\u3068\u6226\u7565\u3092\u63d0\u4f9b\"},\"image\":{\"@id\":\"https:\/\/open-insight.net\/glossary\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u56fa\u5b9a\u91d1\u5229\u3068\u306f - Open Insight \u7528\u8a9e\u96c6\uff1a\u30d3\u30b8\u30cd\u30b9\u306b\u5fc5\u8981\u306a\u7528\u8a9e\u3092\u30ef\u30f3\u30b9\u30c8\u30c3\u30d7\u3067\u7d39\u4ecb","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/open-insight.net\/glossary\/contents\/1690\/","og_locale":"ja_JP","og_type":"article","og_title":"\u56fa\u5b9a\u91d1\u5229\u3068\u306f - Open Insight \u7528\u8a9e\u96c6\uff1a\u30d3\u30b8\u30cd\u30b9\u306b\u5fc5\u8981\u306a\u7528\u8a9e\u3092\u30ef\u30f3\u30b9\u30c8\u30c3\u30d7\u3067\u7d39\u4ecb","og_description":"\u91d1\u878d\u6a5f\u95a2\u306b\u9810\u3051\u5165\u308c\u305f\u969b\u306e\u5e74\u9593\u5229\u606f\u304c\u3001\u671f\u9593\u6e80\u4e86\u307e\u3067\u5909\u52d5\u3057\u306a\u3044\u3001\u4e00\u5b9a\u306e\u91d1\u5229\u3092\u6307\u3057\u307e\u3059\u3002&#8217;","og_url":"https:\/\/open-insight.net\/glossary\/contents\/1690\/","og_site_name":"Open Insight \u7528\u8a9e\u96c6\uff1a\u30d3\u30b8\u30cd\u30b9\u306b\u5fc5\u8981\u306a\u7528\u8a9e\u3092\u30ef\u30f3\u30b9\u30c8\u30c3\u30d7\u3067\u7d39\u4ecb","og_image":[{"width":1200,"height":600,"url":"https:\/\/open-insight.net\/glossary\/wp-content\/uploads\/sites\/2\/2024\/04\/9-6-16-195-1.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/open-insight.net\/glossary\/contents\/1690\/","url":"https:\/\/open-insight.net\/glossary\/contents\/1690\/","name":"\u56fa\u5b9a\u91d1\u5229\u3068\u306f - Open Insight \u7528\u8a9e\u96c6\uff1a\u30d3\u30b8\u30cd\u30b9\u306b\u5fc5\u8981\u306a\u7528\u8a9e\u3092\u30ef\u30f3\u30b9\u30c8\u30c3\u30d7\u3067\u7d39\u4ecb","isPartOf":{"@id":"https:\/\/open-insight.net\/glossary\/#website"},"primaryImageOfPage":{"@id":"https:\/\/open-insight.net\/glossary\/contents\/1690\/#primaryimage"},"image":{"@id":"https:\/\/open-insight.net\/glossary\/contents\/1690\/#primaryimage"},"thumbnailUrl":"https:\/\/open-insight.net\/glossary\/wp-content\/uploads\/sites\/2\/2024\/04\/9-6-16-195-1.png","datePublished":"2024-04-26T02:00:59+00:00","breadcrumb":{"@id":"https:\/\/open-insight.net\/glossary\/contents\/1690\/#breadcrumb"},"inLanguage":"ja","potentialAction":[{"@type":"ReadAction","target":["https:\/\/open-insight.net\/glossary\/contents\/1690\/"]}]},{"@type":"ImageObject","inLanguage":"ja","@id":"https:\/\/open-insight.net\/glossary\/contents\/1690\/#primaryimage","url":"https:\/\/open-insight.net\/glossary\/wp-content\/uploads\/sites\/2\/2024\/04\/9-6-16-195-1.png","contentUrl":"https:\/\/open-insight.net\/glossary\/wp-content\/uploads\/sites\/2\/2024\/04\/9-6-16-195-1.png","width":1200,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/open-insight.net\/glossary\/contents\/1690\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u30db\u30fc\u30e0","item":"https:\/\/open-insight.net\/glossary\/"},{"@type":"ListItem","position":2,"name":"\u7528\u8a9e","item":"https:\/\/open-insight.net\/glossary\/contents\/"},{"@type":"ListItem","position":3,"name":"\u56fa\u5b9a\u91d1\u5229\u3068\u306f"}]},{"@type":"WebSite","@id":"https:\/\/open-insight.net\/glossary\/#website","url":"https:\/\/open-insight.net\/glossary\/","name":"Open Insight \u7528\u8a9e\u96c6\u30b5\u30a4\u30c8\uff1a\u4f01\u696d\u6210\u9577\u306e\u77e5\u898b\u3068\u6226\u7565\u3092\u63d0\u4f9b","description":"Open Insight \u7528\u8a9e\u96c6\u30b5\u30a4\u30c8\u306f\u3001\u4f01\u696d\u306e\u6210\u9577\u3068\u767a\u5c55\u306b\u5fc5\u8981\u306a\u60c5\u5831\u3092\u4e00\u7b87\u6240\u3067\u63d0\u4f9b\u3057\u307e\u3059\u3002","publisher":{"@id":"https:\/\/open-insight.net\/glossary\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/open-insight.net\/glossary\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ja"},{"@type":"Organization","@id":"https:\/\/open-insight.net\/glossary\/#organization","name":"Open Insight \u7528\u8a9e\u96c6\u30b5\u30a4\u30c8\uff1a\u4f01\u696d\u6210\u9577\u306e\u77e5\u898b\u3068\u6226\u7565\u3092\u63d0\u4f9b","url":"https:\/\/open-insight.net\/glossary\/","logo":{"@type":"ImageObject","inLanguage":"ja","@id":"https:\/\/open-insight.net\/glossary\/#\/schema\/logo\/image\/","url":"https:\/\/open-insight.net\/glossary\/wp-content\/uploads\/sites\/2\/2024\/02\/og-image.png","contentUrl":"https:\/\/open-insight.net\/glossary\/wp-content\/uploads\/sites\/2\/2024\/02\/og-image.png","width":1200,"height":675,"caption":"Open Insight \u7528\u8a9e\u96c6\u30b5\u30a4\u30c8\uff1a\u4f01\u696d\u6210\u9577\u306e\u77e5\u898b\u3068\u6226\u7565\u3092\u63d0\u4f9b"},"image":{"@id":"https:\/\/open-insight.net\/glossary\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/open-insight.net\/glossary\/wp-json\/wp\/v2\/contents\/5854","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/open-insight.net\/glossary\/wp-json\/wp\/v2\/contents"}],"about":[{"href":"https:\/\/open-insight.net\/glossary\/wp-json\/wp\/v2\/types\/contents"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/open-insight.net\/glossary\/wp-json\/wp\/v2\/media\/5855"}],"wp:attachment":[{"href":"https:\/\/open-insight.net\/glossary\/wp-json\/wp\/v2\/media?parent=5854"}],"wp:term":[{"taxonomy":"term_category","embeddable":true,"href":"https:\/\/open-insight.net\/glossary\/wp-json\/wp\/v2\/term_category?post=5854"},{"taxonomy":"alphabetical-order","embeddable":true,"href":"https:\/\/open-insight.net\/glossary\/wp-json\/wp\/v2\/alphabetical-order?post=5854"},{"taxonomy":"contents_tag","embeddable":true,"href":"https:\/\/open-insight.net\/glossary\/wp-json\/wp\/v2\/contents_tag?post=5854"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}