{"id":7796,"date":"2024-04-26T17:38:21","date_gmt":"2024-04-26T08:38:21","guid":{"rendered":"https:\/\/open-insight.net\/glossary\/?post_type=contents&#038;p=7796"},"modified":"2024-04-26T17:38:21","modified_gmt":"2024-04-26T08:38:21","slug":"2256","status":"publish","type":"contents","link":"https:\/\/open-insight.net\/glossary\/contents\/2256\/","title":{"rendered":"\u8ef8\u53d7\u3051\u3068\u306f"},"content":{"rendered":"<p>\u8ef8\u306a\u3069\u3092\u652f\u6301\u3059\u308b\u5f79\u5272\u3092\u62c5\u3044\u3001\u56de\u8ee2\u3057\u305f\u308a\u5f80\u5fa9\u904b\u52d5\u3092\u884c\u3046\u76f8\u624b\u90e8\u54c1\u306b\u63a5\u89e6\u3057\u8377\u91cd\u3092\u8ca0\u62c5\u3059\u308b\u90e8\u54c1\u3067\u3042\u308b\u3002&#8217;<\/p>\n","protected":false},"excerpt":{"rendered":"\u8ef8\u306a\u3069\u3092\u652f\u6301\u3059\u308b\u5f79\u5272\u3092\u62c5\u3044\u3001\u56de\u8ee2\u3057\u305f\u308a\u5f80\u5fa9\u904b\u52d5\u3092\u884c\u3046\u76f8\u624b\u90e8\u54c1\u306b\u63a5\u89e6\u3057\u8377\u91cd\u3092\u8ca0\u62c5\u3059\u308b\u90e8\u54c1\u3067\u3042\u308b\u3002&#8217;","protected":false},"featured_media":7797,"template":"","term_category":[133,187],"alphabetical-order":[59,5],"contents_tag":[7483,7484,1277,7485,7486],"class_list":["post-7796","contents","type-contents","status-publish","has-post-thumbnail","hentry","term_category-industry_terminology","term_category-manufacturing_industry","alphabetical-order-ji","alphabetical-order-japanese","contents_tag-7483","contents_tag-7484","contents_tag-1277","contents_tag-7485","contents_tag-7486"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u8ef8\u53d7\u3051\u3068\u306f - Open Insight \u7528\u8a9e\u96c6\uff1a\u30d3\u30b8\u30cd\u30b9\u306b\u5fc5\u8981\u306a\u7528\u8a9e\u3092\u30ef\u30f3\u30b9\u30c8\u30c3\u30d7\u3067\u7d39\u4ecb<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/open-insight.net\/glossary\/contents\/2256\/\" \/>\n<meta property=\"og:locale\" content=\"ja_JP\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u8ef8\u53d7\u3051\u3068\u306f - Open Insight \u7528\u8a9e\u96c6\uff1a\u30d3\u30b8\u30cd\u30b9\u306b\u5fc5\u8981\u306a\u7528\u8a9e\u3092\u30ef\u30f3\u30b9\u30c8\u30c3\u30d7\u3067\u7d39\u4ecb\" \/>\n<meta property=\"og:description\" content=\"\u8ef8\u306a\u3069\u3092\u652f\u6301\u3059\u308b\u5f79\u5272\u3092\u62c5\u3044\u3001\u56de\u8ee2\u3057\u305f\u308a\u5f80\u5fa9\u904b\u52d5\u3092\u884c\u3046\u76f8\u624b\u90e8\u54c1\u306b\u63a5\u89e6\u3057\u8377\u91cd\u3092\u8ca0\u62c5\u3059\u308b\u90e8\u54c1\u3067\u3042\u308b\u3002&#8217;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/open-insight.net\/glossary\/contents\/2256\/\" \/>\n<meta property=\"og:site_name\" content=\"Open Insight \u7528\u8a9e\u96c6\uff1a\u30d3\u30b8\u30cd\u30b9\u306b\u5fc5\u8981\u306a\u7528\u8a9e\u3092\u30ef\u30f3\u30b9\u30c8\u30c3\u30d7\u3067\u7d39\u4ecb\" \/>\n<meta property=\"og:image\" content=\"https:\/\/open-insight.net\/glossary\/wp-content\/uploads\/sites\/2\/2024\/04\/9-8-16-163-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/open-insight.net\/glossary\/contents\/2256\/\",\"url\":\"https:\/\/open-insight.net\/glossary\/contents\/2256\/\",\"name\":\"\u8ef8\u53d7\u3051\u3068\u306f - Open Insight \u7528\u8a9e\u96c6\uff1a\u30d3\u30b8\u30cd\u30b9\u306b\u5fc5\u8981\u306a\u7528\u8a9e\u3092\u30ef\u30f3\u30b9\u30c8\u30c3\u30d7\u3067\u7d39\u4ecb\",\"isPartOf\":{\"@id\":\"https:\/\/open-insight.net\/glossary\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/open-insight.net\/glossary\/contents\/2256\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/open-insight.net\/glossary\/contents\/2256\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/open-insight.net\/glossary\/wp-content\/uploads\/sites\/2\/2024\/04\/9-8-16-163-1.png\",\"datePublished\":\"2024-04-26T08:38:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/open-insight.net\/glossary\/contents\/2256\/#breadcrumb\"},\"inLanguage\":\"ja\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/open-insight.net\/glossary\/contents\/2256\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ja\",\"@id\":\"https:\/\/open-insight.net\/glossary\/contents\/2256\/#primaryimage\",\"url\":\"https:\/\/open-insight.net\/glossary\/wp-content\/uploads\/sites\/2\/2024\/04\/9-8-16-163-1.png\",\"contentUrl\":\"https:\/\/open-insight.net\/glossary\/wp-content\/uploads\/sites\/2\/2024\/04\/9-8-16-163-1.png\",\"width\":1200,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/open-insight.net\/glossary\/contents\/2256\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u30db\u30fc\u30e0\",\"item\":\"https:\/\/open-insight.net\/glossary\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u7528\u8a9e\",\"item\":\"https:\/\/open-insight.net\/glossary\/contents\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u8ef8\u53d7\u3051\u3068\u306f\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/open-insight.net\/glossary\/#website\",\"url\":\"https:\/\/open-insight.net\/glossary\/\",\"name\":\"Open Insight \u7528\u8a9e\u96c6\u30b5\u30a4\u30c8\uff1a\u4f01\u696d\u6210\u9577\u306e\u77e5\u898b\u3068\u6226\u7565\u3092\u63d0\u4f9b\",\"description\":\"Open Insight \u7528\u8a9e\u96c6\u30b5\u30a4\u30c8\u306f\u3001\u4f01\u696d\u306e\u6210\u9577\u3068\u767a\u5c55\u306b\u5fc5\u8981\u306a\u60c5\u5831\u3092\u4e00\u7b87\u6240\u3067\u63d0\u4f9b\u3057\u307e\u3059\u3002\",\"publisher\":{\"@id\":\"https:\/\/open-insight.net\/glossary\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/open-insight.net\/glossary\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ja\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/open-insight.net\/glossary\/#organization\",\"name\":\"Open Insight \u7528\u8a9e\u96c6\u30b5\u30a4\u30c8\uff1a\u4f01\u696d\u6210\u9577\u306e\u77e5\u898b\u3068\u6226\u7565\u3092\u63d0\u4f9b\",\"url\":\"https:\/\/open-insight.net\/glossary\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ja\",\"@id\":\"https:\/\/open-insight.net\/glossary\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/open-insight.net\/glossary\/wp-content\/uploads\/sites\/2\/2024\/02\/og-image.png\",\"contentUrl\":\"https:\/\/open-insight.net\/glossary\/wp-content\/uploads\/sites\/2\/2024\/02\/og-image.png\",\"width\":1200,\"height\":675,\"caption\":\"Open Insight \u7528\u8a9e\u96c6\u30b5\u30a4\u30c8\uff1a\u4f01\u696d\u6210\u9577\u306e\u77e5\u898b\u3068\u6226\u7565\u3092\u63d0\u4f9b\"},\"image\":{\"@id\":\"https:\/\/open-insight.net\/glossary\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u8ef8\u53d7\u3051\u3068\u306f - Open Insight \u7528\u8a9e\u96c6\uff1a\u30d3\u30b8\u30cd\u30b9\u306b\u5fc5\u8981\u306a\u7528\u8a9e\u3092\u30ef\u30f3\u30b9\u30c8\u30c3\u30d7\u3067\u7d39\u4ecb","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/open-insight.net\/glossary\/contents\/2256\/","og_locale":"ja_JP","og_type":"article","og_title":"\u8ef8\u53d7\u3051\u3068\u306f - Open Insight \u7528\u8a9e\u96c6\uff1a\u30d3\u30b8\u30cd\u30b9\u306b\u5fc5\u8981\u306a\u7528\u8a9e\u3092\u30ef\u30f3\u30b9\u30c8\u30c3\u30d7\u3067\u7d39\u4ecb","og_description":"\u8ef8\u306a\u3069\u3092\u652f\u6301\u3059\u308b\u5f79\u5272\u3092\u62c5\u3044\u3001\u56de\u8ee2\u3057\u305f\u308a\u5f80\u5fa9\u904b\u52d5\u3092\u884c\u3046\u76f8\u624b\u90e8\u54c1\u306b\u63a5\u89e6\u3057\u8377\u91cd\u3092\u8ca0\u62c5\u3059\u308b\u90e8\u54c1\u3067\u3042\u308b\u3002&#8217;","og_url":"https:\/\/open-insight.net\/glossary\/contents\/2256\/","og_site_name":"Open Insight \u7528\u8a9e\u96c6\uff1a\u30d3\u30b8\u30cd\u30b9\u306b\u5fc5\u8981\u306a\u7528\u8a9e\u3092\u30ef\u30f3\u30b9\u30c8\u30c3\u30d7\u3067\u7d39\u4ecb","og_image":[{"width":1200,"height":600,"url":"https:\/\/open-insight.net\/glossary\/wp-content\/uploads\/sites\/2\/2024\/04\/9-8-16-163-1.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/open-insight.net\/glossary\/contents\/2256\/","url":"https:\/\/open-insight.net\/glossary\/contents\/2256\/","name":"\u8ef8\u53d7\u3051\u3068\u306f - Open Insight \u7528\u8a9e\u96c6\uff1a\u30d3\u30b8\u30cd\u30b9\u306b\u5fc5\u8981\u306a\u7528\u8a9e\u3092\u30ef\u30f3\u30b9\u30c8\u30c3\u30d7\u3067\u7d39\u4ecb","isPartOf":{"@id":"https:\/\/open-insight.net\/glossary\/#website"},"primaryImageOfPage":{"@id":"https:\/\/open-insight.net\/glossary\/contents\/2256\/#primaryimage"},"image":{"@id":"https:\/\/open-insight.net\/glossary\/contents\/2256\/#primaryimage"},"thumbnailUrl":"https:\/\/open-insight.net\/glossary\/wp-content\/uploads\/sites\/2\/2024\/04\/9-8-16-163-1.png","datePublished":"2024-04-26T08:38:21+00:00","breadcrumb":{"@id":"https:\/\/open-insight.net\/glossary\/contents\/2256\/#breadcrumb"},"inLanguage":"ja","potentialAction":[{"@type":"ReadAction","target":["https:\/\/open-insight.net\/glossary\/contents\/2256\/"]}]},{"@type":"ImageObject","inLanguage":"ja","@id":"https:\/\/open-insight.net\/glossary\/contents\/2256\/#primaryimage","url":"https:\/\/open-insight.net\/glossary\/wp-content\/uploads\/sites\/2\/2024\/04\/9-8-16-163-1.png","contentUrl":"https:\/\/open-insight.net\/glossary\/wp-content\/uploads\/sites\/2\/2024\/04\/9-8-16-163-1.png","width":1200,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/open-insight.net\/glossary\/contents\/2256\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u30db\u30fc\u30e0","item":"https:\/\/open-insight.net\/glossary\/"},{"@type":"ListItem","position":2,"name":"\u7528\u8a9e","item":"https:\/\/open-insight.net\/glossary\/contents\/"},{"@type":"ListItem","position":3,"name":"\u8ef8\u53d7\u3051\u3068\u306f"}]},{"@type":"WebSite","@id":"https:\/\/open-insight.net\/glossary\/#website","url":"https:\/\/open-insight.net\/glossary\/","name":"Open Insight \u7528\u8a9e\u96c6\u30b5\u30a4\u30c8\uff1a\u4f01\u696d\u6210\u9577\u306e\u77e5\u898b\u3068\u6226\u7565\u3092\u63d0\u4f9b","description":"Open Insight \u7528\u8a9e\u96c6\u30b5\u30a4\u30c8\u306f\u3001\u4f01\u696d\u306e\u6210\u9577\u3068\u767a\u5c55\u306b\u5fc5\u8981\u306a\u60c5\u5831\u3092\u4e00\u7b87\u6240\u3067\u63d0\u4f9b\u3057\u307e\u3059\u3002","publisher":{"@id":"https:\/\/open-insight.net\/glossary\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/open-insight.net\/glossary\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ja"},{"@type":"Organization","@id":"https:\/\/open-insight.net\/glossary\/#organization","name":"Open Insight \u7528\u8a9e\u96c6\u30b5\u30a4\u30c8\uff1a\u4f01\u696d\u6210\u9577\u306e\u77e5\u898b\u3068\u6226\u7565\u3092\u63d0\u4f9b","url":"https:\/\/open-insight.net\/glossary\/","logo":{"@type":"ImageObject","inLanguage":"ja","@id":"https:\/\/open-insight.net\/glossary\/#\/schema\/logo\/image\/","url":"https:\/\/open-insight.net\/glossary\/wp-content\/uploads\/sites\/2\/2024\/02\/og-image.png","contentUrl":"https:\/\/open-insight.net\/glossary\/wp-content\/uploads\/sites\/2\/2024\/02\/og-image.png","width":1200,"height":675,"caption":"Open Insight \u7528\u8a9e\u96c6\u30b5\u30a4\u30c8\uff1a\u4f01\u696d\u6210\u9577\u306e\u77e5\u898b\u3068\u6226\u7565\u3092\u63d0\u4f9b"},"image":{"@id":"https:\/\/open-insight.net\/glossary\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/open-insight.net\/glossary\/wp-json\/wp\/v2\/contents\/7796","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/open-insight.net\/glossary\/wp-json\/wp\/v2\/contents"}],"about":[{"href":"https:\/\/open-insight.net\/glossary\/wp-json\/wp\/v2\/types\/contents"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/open-insight.net\/glossary\/wp-json\/wp\/v2\/media\/7797"}],"wp:attachment":[{"href":"https:\/\/open-insight.net\/glossary\/wp-json\/wp\/v2\/media?parent=7796"}],"wp:term":[{"taxonomy":"term_category","embeddable":true,"href":"https:\/\/open-insight.net\/glossary\/wp-json\/wp\/v2\/term_category?post=7796"},{"taxonomy":"alphabetical-order","embeddable":true,"href":"https:\/\/open-insight.net\/glossary\/wp-json\/wp\/v2\/alphabetical-order?post=7796"},{"taxonomy":"contents_tag","embeddable":true,"href":"https:\/\/open-insight.net\/glossary\/wp-json\/wp\/v2\/contents_tag?post=7796"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}