{"id":13979,"count":2,"description":"","link":"https:\/\/open-insight.net\/glossary\/contents_tag\/%e3%83%ad%e3%82%b0%e8%a7%a3%e6%9e%90\/","name":"\u30ed\u30b0\u89e3\u6790","slug":"%e3%83%ad%e3%82%b0%e8%a7%a3%e6%9e%90","taxonomy":"contents_tag","meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u30ed\u30b0\u89e3\u6790 \u30a2\u30fc\u30ab\u30a4\u30d6 - Open Insight \u7528\u8a9e\u96c6\uff1a\u30d3\u30b8\u30cd\u30b9\u306b\u5fc5\u8981\u306a\u7528\u8a9e\u3092\u30ef\u30f3\u30b9\u30c8\u30c3\u30d7\u3067\u7d39\u4ecb<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/open-insight.net\/glossary\/contents_tag\/\u30ed\u30b0\u89e3\u6790\/\" \/>\n<meta property=\"og:locale\" content=\"ja_JP\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u30ed\u30b0\u89e3\u6790 \u30a2\u30fc\u30ab\u30a4\u30d6 - Open Insight \u7528\u8a9e\u96c6\uff1a\u30d3\u30b8\u30cd\u30b9\u306b\u5fc5\u8981\u306a\u7528\u8a9e\u3092\u30ef\u30f3\u30b9\u30c8\u30c3\u30d7\u3067\u7d39\u4ecb\" \/>\n<meta property=\"og:url\" content=\"https:\/\/open-insight.net\/glossary\/contents_tag\/\u30ed\u30b0\u89e3\u6790\/\" \/>\n<meta property=\"og:site_name\" content=\"Open Insight \u7528\u8a9e\u96c6\uff1a\u30d3\u30b8\u30cd\u30b9\u306b\u5fc5\u8981\u306a\u7528\u8a9e\u3092\u30ef\u30f3\u30b9\u30c8\u30c3\u30d7\u3067\u7d39\u4ecb\" \/>\n<meta property=\"og:image\" content=\"https:\/\/open-insight.net\/glossary\/wp-content\/uploads\/sites\/2\/2024\/02\/Open-Insight-Logo.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1505\" \/>\n\t<meta property=\"og:image:height\" content=\"325\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/open-insight.net\/glossary\/contents_tag\/%e3%83%ad%e3%82%b0%e8%a7%a3%e6%9e%90\/\",\"url\":\"https:\/\/open-insight.net\/glossary\/contents_tag\/%e3%83%ad%e3%82%b0%e8%a7%a3%e6%9e%90\/\",\"name\":\"\u30ed\u30b0\u89e3\u6790 \u30a2\u30fc\u30ab\u30a4\u30d6 - Open Insight \u7528\u8a9e\u96c6\uff1a\u30d3\u30b8\u30cd\u30b9\u306b\u5fc5\u8981\u306a\u7528\u8a9e\u3092\u30ef\u30f3\u30b9\u30c8\u30c3\u30d7\u3067\u7d39\u4ecb\",\"isPartOf\":{\"@id\":\"https:\/\/open-insight.net\/glossary\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/open-insight.net\/glossary\/contents_tag\/%e3%83%ad%e3%82%b0%e8%a7%a3%e6%9e%90\/#breadcrumb\"},\"inLanguage\":\"ja\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/open-insight.net\/glossary\/contents_tag\/%e3%83%ad%e3%82%b0%e8%a7%a3%e6%9e%90\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u30db\u30fc\u30e0\",\"item\":\"https:\/\/open-insight.net\/glossary\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u30ed\u30b0\u89e3\u6790\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/open-insight.net\/glossary\/#website\",\"url\":\"https:\/\/open-insight.net\/glossary\/\",\"name\":\"Open Insight \u7528\u8a9e\u96c6\u30b5\u30a4\u30c8\uff1a\u4f01\u696d\u6210\u9577\u306e\u77e5\u898b\u3068\u6226\u7565\u3092\u63d0\u4f9b\",\"description\":\"Open Insight \u7528\u8a9e\u96c6\u30b5\u30a4\u30c8\u306f\u3001\u4f01\u696d\u306e\u6210\u9577\u3068\u767a\u5c55\u306b\u5fc5\u8981\u306a\u60c5\u5831\u3092\u4e00\u7b87\u6240\u3067\u63d0\u4f9b\u3057\u307e\u3059\u3002\",\"publisher\":{\"@id\":\"https:\/\/open-insight.net\/glossary\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/open-insight.net\/glossary\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ja\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/open-insight.net\/glossary\/#organization\",\"name\":\"Open Insight \u7528\u8a9e\u96c6\u30b5\u30a4\u30c8\uff1a\u4f01\u696d\u6210\u9577\u306e\u77e5\u898b\u3068\u6226\u7565\u3092\u63d0\u4f9b\",\"url\":\"https:\/\/open-insight.net\/glossary\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ja\",\"@id\":\"https:\/\/open-insight.net\/glossary\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/open-insight.net\/glossary\/wp-content\/uploads\/sites\/2\/2024\/02\/og-image.png\",\"contentUrl\":\"https:\/\/open-insight.net\/glossary\/wp-content\/uploads\/sites\/2\/2024\/02\/og-image.png\",\"width\":1200,\"height\":675,\"caption\":\"Open Insight \u7528\u8a9e\u96c6\u30b5\u30a4\u30c8\uff1a\u4f01\u696d\u6210\u9577\u306e\u77e5\u898b\u3068\u6226\u7565\u3092\u63d0\u4f9b\"},\"image\":{\"@id\":\"https:\/\/open-insight.net\/glossary\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u30ed\u30b0\u89e3\u6790 \u30a2\u30fc\u30ab\u30a4\u30d6 - Open Insight \u7528\u8a9e\u96c6\uff1a\u30d3\u30b8\u30cd\u30b9\u306b\u5fc5\u8981\u306a\u7528\u8a9e\u3092\u30ef\u30f3\u30b9\u30c8\u30c3\u30d7\u3067\u7d39\u4ecb","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/open-insight.net\/glossary\/contents_tag\/\u30ed\u30b0\u89e3\u6790\/","og_locale":"ja_JP","og_type":"article","og_title":"\u30ed\u30b0\u89e3\u6790 \u30a2\u30fc\u30ab\u30a4\u30d6 - Open Insight \u7528\u8a9e\u96c6\uff1a\u30d3\u30b8\u30cd\u30b9\u306b\u5fc5\u8981\u306a\u7528\u8a9e\u3092\u30ef\u30f3\u30b9\u30c8\u30c3\u30d7\u3067\u7d39\u4ecb","og_url":"https:\/\/open-insight.net\/glossary\/contents_tag\/\u30ed\u30b0\u89e3\u6790\/","og_site_name":"Open Insight \u7528\u8a9e\u96c6\uff1a\u30d3\u30b8\u30cd\u30b9\u306b\u5fc5\u8981\u306a\u7528\u8a9e\u3092\u30ef\u30f3\u30b9\u30c8\u30c3\u30d7\u3067\u7d39\u4ecb","og_image":[{"width":1505,"height":325,"url":"https:\/\/open-insight.net\/glossary\/wp-content\/uploads\/sites\/2\/2024\/02\/Open-Insight-Logo.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/open-insight.net\/glossary\/contents_tag\/%e3%83%ad%e3%82%b0%e8%a7%a3%e6%9e%90\/","url":"https:\/\/open-insight.net\/glossary\/contents_tag\/%e3%83%ad%e3%82%b0%e8%a7%a3%e6%9e%90\/","name":"\u30ed\u30b0\u89e3\u6790 \u30a2\u30fc\u30ab\u30a4\u30d6 - Open Insight \u7528\u8a9e\u96c6\uff1a\u30d3\u30b8\u30cd\u30b9\u306b\u5fc5\u8981\u306a\u7528\u8a9e\u3092\u30ef\u30f3\u30b9\u30c8\u30c3\u30d7\u3067\u7d39\u4ecb","isPartOf":{"@id":"https:\/\/open-insight.net\/glossary\/#website"},"breadcrumb":{"@id":"https:\/\/open-insight.net\/glossary\/contents_tag\/%e3%83%ad%e3%82%b0%e8%a7%a3%e6%9e%90\/#breadcrumb"},"inLanguage":"ja"},{"@type":"BreadcrumbList","@id":"https:\/\/open-insight.net\/glossary\/contents_tag\/%e3%83%ad%e3%82%b0%e8%a7%a3%e6%9e%90\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u30db\u30fc\u30e0","item":"https:\/\/open-insight.net\/glossary\/"},{"@type":"ListItem","position":2,"name":"\u30ed\u30b0\u89e3\u6790"}]},{"@type":"WebSite","@id":"https:\/\/open-insight.net\/glossary\/#website","url":"https:\/\/open-insight.net\/glossary\/","name":"Open Insight \u7528\u8a9e\u96c6\u30b5\u30a4\u30c8\uff1a\u4f01\u696d\u6210\u9577\u306e\u77e5\u898b\u3068\u6226\u7565\u3092\u63d0\u4f9b","description":"Open Insight \u7528\u8a9e\u96c6\u30b5\u30a4\u30c8\u306f\u3001\u4f01\u696d\u306e\u6210\u9577\u3068\u767a\u5c55\u306b\u5fc5\u8981\u306a\u60c5\u5831\u3092\u4e00\u7b87\u6240\u3067\u63d0\u4f9b\u3057\u307e\u3059\u3002","publisher":{"@id":"https:\/\/open-insight.net\/glossary\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/open-insight.net\/glossary\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ja"},{"@type":"Organization","@id":"https:\/\/open-insight.net\/glossary\/#organization","name":"Open Insight \u7528\u8a9e\u96c6\u30b5\u30a4\u30c8\uff1a\u4f01\u696d\u6210\u9577\u306e\u77e5\u898b\u3068\u6226\u7565\u3092\u63d0\u4f9b","url":"https:\/\/open-insight.net\/glossary\/","logo":{"@type":"ImageObject","inLanguage":"ja","@id":"https:\/\/open-insight.net\/glossary\/#\/schema\/logo\/image\/","url":"https:\/\/open-insight.net\/glossary\/wp-content\/uploads\/sites\/2\/2024\/02\/og-image.png","contentUrl":"https:\/\/open-insight.net\/glossary\/wp-content\/uploads\/sites\/2\/2024\/02\/og-image.png","width":1200,"height":675,"caption":"Open Insight \u7528\u8a9e\u96c6\u30b5\u30a4\u30c8\uff1a\u4f01\u696d\u6210\u9577\u306e\u77e5\u898b\u3068\u6226\u7565\u3092\u63d0\u4f9b"},"image":{"@id":"https:\/\/open-insight.net\/glossary\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/open-insight.net\/glossary\/wp-json\/wp\/v2\/contents_tag\/13979","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/open-insight.net\/glossary\/wp-json\/wp\/v2\/contents_tag"}],"about":[{"href":"https:\/\/open-insight.net\/glossary\/wp-json\/wp\/v2\/taxonomies\/contents_tag"}],"wp:post_type":[{"href":"https:\/\/open-insight.net\/glossary\/wp-json\/wp\/v2\/contents?contents_tag=13979"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}